{"id":4395,"date":"2025-11-17T15:32:22","date_gmt":"2025-11-17T14:32:22","guid":{"rendered":"https:\/\/www.visital.no\/?post_type=tribe_events&#038;p=4395"},"modified":"2025-11-17T15:32:22","modified_gmt":"2025-11-17T14:32:22","slug":"offisiell-apning-av-hallingdal-bilvask","status":"publish","type":"tribe_events","link":"https:\/\/www.visital.no\/en\/arrangementer\/offisiell-apning-av-hallingdal-bilvask\/","title":{"rendered":"Official opening of Hallingdal car wash"},"content":{"rendered":"<p>In connection with the opening, all washes will be half price on Saturday 13 December and Sunday 14 December. The supplier of the washing equipment will be present on both days, and visitors will be able to get answers to questions and information about the facility. There will also be light refreshments for everyone who stops by.<\/p>","protected":false},"excerpt":{"rendered":"<p>Hallingdal Bilvask is celebrating the opening of its new car wash in \u00c5l, and invites both new and old customers to a pleasant opening weekend.<\/p>","protected":false},"author":3,"featured_media":4396,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-4395","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<title>Offisiell \u00e5pning av Hallingdal bilvask - Visit \u00c5l<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offisiell \u00e5pning av Hallingdal bilvask - Visit \u00c5l\" \/>\n<meta property=\"og:description\" content=\"Hallingdal Bilvask markerer \u00e5pningen av sine nye vaskehaller p\u00e5 \u00c5l, og inviterer til en hyggelig \u00e5pningshelg for b\u00e5de nye og gamle kunder.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visital.no\/en\/arrangementer\/offisiell-apning-av-hallingdal-bilvask\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit \u00c5l\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/visitalihallingdal\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visital.no\/wp-content\/uploads\/2025\/11\/581513393-122102961945110546-1900758956653982900-n.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"934\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/offisiell-apning-av-hallingdal-bilvask\\\/\",\"url\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/offisiell-apning-av-hallingdal-bilvask\\\/\",\"name\":\"Offisiell \u00e5pning av Hallingdal bilvask - Visit \u00c5l\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visital.no\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/offisiell-apning-av-hallingdal-bilvask\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/offisiell-apning-av-hallingdal-bilvask\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visital.no\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/581513393-122102961945110546-1900758956653982900-n.webp\",\"datePublished\":\"2025-11-17T14:32:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/offisiell-apning-av-hallingdal-bilvask\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/offisiell-apning-av-hallingdal-bilvask\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/offisiell-apning-av-hallingdal-bilvask\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.visital.no\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/581513393-122102961945110546-1900758956653982900-n.webp\",\"contentUrl\":\"https:\\\/\\\/www.visital.no\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/581513393-122102961945110546-1900758956653982900-n.webp\",\"width\":2000,\"height\":934,\"caption\":\"Bilde av Hallingdal bilvask\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/offisiell-apning-av-hallingdal-bilvask\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.visital.no\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arrangementer\",\"item\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Offisiell \u00e5pning av Hallingdal bilvask\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.visital.no\\\/#website\",\"url\":\"https:\\\/\\\/www.visital.no\\\/\",\"name\":\"Visit \u00c5l\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.visital.no\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.visital.no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.visital.no\\\/#organization\",\"name\":\"Visit \u00c5l\",\"url\":\"https:\\\/\\\/www.visital.no\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.visital.no\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.visital.no\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/al-i-hallingdal-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.visital.no\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/al-i-hallingdal-logo.svg\",\"width\":258,\"height\":100,\"caption\":\"Visit \u00c5l\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visital.no\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/visitalihallingdal\\\/\",\"https:\\\/\\\/instagram.com\\\/visitalihallingdal\\\/\",\"https:\\\/\\\/youtube.com\\\/user\\\/alutvikling\"]}]}<\/script>","yoast_head_json":{"title":"Official opening of Hallingdal car wash - Visit \u00c5l","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"Offisiell \u00e5pning av Hallingdal bilvask - Visit \u00c5l","og_description":"Hallingdal Bilvask markerer \u00e5pningen av sine nye vaskehaller p\u00e5 \u00c5l, og inviterer til en hyggelig \u00e5pningshelg for b\u00e5de nye og gamle kunder.","og_url":"https:\/\/www.visital.no\/en\/arrangementer\/offisiell-apning-av-hallingdal-bilvask\/","og_site_name":"Visit \u00c5l","article_publisher":"https:\/\/facebook.com\/visitalihallingdal\/","og_image":[{"width":2000,"height":934,"url":"https:\/\/www.visital.no\/wp-content\/uploads\/2025\/11\/581513393-122102961945110546-1900758956653982900-n.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.visital.no\/arrangementer\/offisiell-apning-av-hallingdal-bilvask\/","url":"https:\/\/www.visital.no\/arrangementer\/offisiell-apning-av-hallingdal-bilvask\/","name":"Official opening of Hallingdal car wash - Visit \u00c5l","isPartOf":{"@id":"https:\/\/www.visital.no\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.visital.no\/arrangementer\/offisiell-apning-av-hallingdal-bilvask\/#primaryimage"},"image":{"@id":"https:\/\/www.visital.no\/arrangementer\/offisiell-apning-av-hallingdal-bilvask\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visital.no\/wp-content\/uploads\/2025\/11\/581513393-122102961945110546-1900758956653982900-n.webp","datePublished":"2025-11-17T14:32:22+00:00","breadcrumb":{"@id":"https:\/\/www.visital.no\/arrangementer\/offisiell-apning-av-hallingdal-bilvask\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visital.no\/arrangementer\/offisiell-apning-av-hallingdal-bilvask\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.visital.no\/arrangementer\/offisiell-apning-av-hallingdal-bilvask\/#primaryimage","url":"https:\/\/www.visital.no\/wp-content\/uploads\/2025\/11\/581513393-122102961945110546-1900758956653982900-n.webp","contentUrl":"https:\/\/www.visital.no\/wp-content\/uploads\/2025\/11\/581513393-122102961945110546-1900758956653982900-n.webp","width":2000,"height":934,"caption":"Bilde av Hallingdal bilvask"},{"@type":"BreadcrumbList","@id":"https:\/\/www.visital.no\/arrangementer\/offisiell-apning-av-hallingdal-bilvask\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.visital.no\/"},{"@type":"ListItem","position":2,"name":"Arrangementer","item":"https:\/\/www.visital.no\/arrangementer\/"},{"@type":"ListItem","position":3,"name":"Offisiell \u00e5pning av Hallingdal bilvask"}]},{"@type":"WebSite","@id":"https:\/\/www.visital.no\/#website","url":"https:\/\/www.visital.no\/","name":"Visit \u00c5l","description":"","publisher":{"@id":"https:\/\/www.visital.no\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visital.no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.visital.no\/#organization","name":"Visit \u00c5l","url":"https:\/\/www.visital.no\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.visital.no\/#\/schema\/logo\/image\/","url":"https:\/\/www.visital.no\/wp-content\/uploads\/2024\/11\/al-i-hallingdal-logo.svg","contentUrl":"https:\/\/www.visital.no\/wp-content\/uploads\/2024\/11\/al-i-hallingdal-logo.svg","width":258,"height":100,"caption":"Visit \u00c5l"},"image":{"@id":"https:\/\/www.visital.no\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/visitalihallingdal\/","https:\/\/instagram.com\/visitalihallingdal\/","https:\/\/youtube.com\/user\/alutvikling"]}]}},"_links":{"self":[{"href":"https:\/\/www.visital.no\/en\/wp-json\/wp\/v2\/tribe_events\/4395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.visital.no\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.visital.no\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.visital.no\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/www.visital.no\/en\/wp-json\/wp\/v2\/tribe_events\/4395\/revisions"}],"predecessor-version":[{"id":4399,"href":"https:\/\/www.visital.no\/en\/wp-json\/wp\/v2\/tribe_events\/4395\/revisions\/4399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visital.no\/en\/wp-json\/wp\/v2\/media\/4396"}],"wp:attachment":[{"href":"https:\/\/www.visital.no\/en\/wp-json\/wp\/v2\/media?parent=4395"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.visital.no\/en\/wp-json\/wp\/v2\/tags?post=4395"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.visital.no\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=4395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}