{"id":3905,"date":"2025-09-11T15:09:24","date_gmt":"2025-09-11T13:09:24","guid":{"rendered":"https:\/\/www.visital.no\/?post_type=tribe_events&#038;p=3905"},"modified":"2025-09-11T15:09:24","modified_gmt":"2025-09-11T13:09:24","slug":"sundre-i-hundre-2","status":"publish","type":"tribe_events","link":"https:\/\/www.visital.no\/de\/arrangementer\/sundre-i-hundre-2\/","title":{"rendered":"Sundre in Hunderten"},"content":{"rendered":"<p>Die Auff\u00fchrung versetzt die Zuschauer zur\u00fcck auf einen Sundretorg-Platz voller Leben, kleiner Gesch\u00e4fte, Originale und guter Geschichten. Hier erinnern wir uns an ein lokales Umfeld, in dem man in den Caf\u00e9s die neuesten Nachrichten h\u00f6ren, bei Nr. 15 oder den Pferdest\u00e4llen vorbeischauen und ein Dorf mit Kindern in jedem Haus, Spiel, Spa\u00df und Sicherheit nebeneinander erleben konnte.<\/p>\n<p>Mit einer gro\u00dfen Portion Humor und Ernsthaftigkeit erz\u00e4hlen Berg und Brye die gro\u00dfe Geschichte von Sundre - vom Spielring in Solhov und dem Jugendclub im Folkets Hus bis zu Wunschkonzerten in der Sundrehall, Alkohol am Steuer, Popkultur, Softdrinks und Fernsehen. Ausgew\u00e4hlte Bilder aus einem ganzen Jahrhundert stammen aus vielen Quellen und sorgen beim Publikum f\u00fcr Lacher, Nostalgie und nachdenkliche Momente.<\/p>\n<p>Neben ihnen stehen die Kommentatoren Alf Sonerud, Gudveig Fingarsen und Tor Egil Bu\u00f8en auf der B\u00fchne, die diesem historisch-humorvollen Abend den letzten Schliff geben.<\/p>","protected":false},"excerpt":{"rendered":"<p>Am Dienstag, dem 9. Dezember, um 19.00 Uhr und am Samstag, dem 27. Dezember, um 15.00 Uhr werden Hallgrim Berg und Ole Johs Brye mit ihrem St\u00fcck Sundre i hundre den gro\u00dfen Saal des \u00c5l kulturhus mit Lachen und Erinnerungen f\u00fcllen.<\/p>","protected":false},"author":3,"featured_media":3902,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[144],"class_list":["post-3905","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-foredrag","cat_foredrag"],"acf":[],"yoast_head":"<title>Sundre i hundre - Visit \u00c5l<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sundre i hundre - Visit \u00c5l\" \/>\n<meta property=\"og:description\" content=\"Tirsdag 9. desember kl. 19.00 og l\u00f8rdag 27. desember kl. 15.00 fylles Storesalen i \u00c5l kulturhus med b\u00e5de latter og minner n\u00e5r Hallgrim Berg og Ole Johs Brye inviterer til forestillingen Sundre i hundre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visital.no\/de\/arrangementer\/sundre-i-hundre-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit \u00c5l\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/visitalihallingdal\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visital.no\/wp-content\/uploads\/2025\/09\/178918.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1324\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/sundre-i-hundre-2\\\/\",\"url\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/sundre-i-hundre-2\\\/\",\"name\":\"Sundre i hundre - Visit \u00c5l\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visital.no\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/sundre-i-hundre-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/sundre-i-hundre-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visital.no\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/178918.webp\",\"datePublished\":\"2025-09-11T13:09:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/sundre-i-hundre-2\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/sundre-i-hundre-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/sundre-i-hundre-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.visital.no\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/178918.webp\",\"contentUrl\":\"https:\\\/\\\/www.visital.no\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/178918.webp\",\"width\":1920,\"height\":1324},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/sundre-i-hundre-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.visital.no\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arrangementer\",\"item\":\"https:\\\/\\\/www.visital.no\\\/arrangementer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sundre i hundre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.visital.no\\\/#website\",\"url\":\"https:\\\/\\\/www.visital.no\\\/\",\"name\":\"Visit \u00c5l\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.visital.no\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.visital.no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.visital.no\\\/#organization\",\"name\":\"Visit \u00c5l\",\"url\":\"https:\\\/\\\/www.visital.no\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.visital.no\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.visital.no\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/al-i-hallingdal-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.visital.no\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/al-i-hallingdal-logo.svg\",\"width\":258,\"height\":100,\"caption\":\"Visit \u00c5l\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visital.no\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/visitalihallingdal\\\/\",\"https:\\\/\\\/instagram.com\\\/visitalihallingdal\\\/\",\"https:\\\/\\\/youtube.com\\\/user\\\/alutvikling\"]}]}<\/script>","yoast_head_json":{"title":"Sundre i hundre - Besuchen Sie \u00c5l","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Sundre i hundre - Visit \u00c5l","og_description":"Tirsdag 9. desember kl. 19.00 og l\u00f8rdag 27. desember kl. 15.00 fylles Storesalen i \u00c5l kulturhus med b\u00e5de latter og minner n\u00e5r Hallgrim Berg og Ole Johs Brye inviterer til forestillingen Sundre i hundre.","og_url":"https:\/\/www.visital.no\/de\/arrangementer\/sundre-i-hundre-2\/","og_site_name":"Visit \u00c5l","article_publisher":"https:\/\/facebook.com\/visitalihallingdal\/","og_image":[{"width":1920,"height":1324,"url":"https:\/\/www.visital.no\/wp-content\/uploads\/2025\/09\/178918.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.visital.no\/arrangementer\/sundre-i-hundre-2\/","url":"https:\/\/www.visital.no\/arrangementer\/sundre-i-hundre-2\/","name":"Sundre i hundre - Besuchen Sie \u00c5l","isPartOf":{"@id":"https:\/\/www.visital.no\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.visital.no\/arrangementer\/sundre-i-hundre-2\/#primaryimage"},"image":{"@id":"https:\/\/www.visital.no\/arrangementer\/sundre-i-hundre-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visital.no\/wp-content\/uploads\/2025\/09\/178918.webp","datePublished":"2025-09-11T13:09:24+00:00","breadcrumb":{"@id":"https:\/\/www.visital.no\/arrangementer\/sundre-i-hundre-2\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visital.no\/arrangementer\/sundre-i-hundre-2\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.visital.no\/arrangementer\/sundre-i-hundre-2\/#primaryimage","url":"https:\/\/www.visital.no\/wp-content\/uploads\/2025\/09\/178918.webp","contentUrl":"https:\/\/www.visital.no\/wp-content\/uploads\/2025\/09\/178918.webp","width":1920,"height":1324},{"@type":"BreadcrumbList","@id":"https:\/\/www.visital.no\/arrangementer\/sundre-i-hundre-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.visital.no\/"},{"@type":"ListItem","position":2,"name":"Arrangementer","item":"https:\/\/www.visital.no\/arrangementer\/"},{"@type":"ListItem","position":3,"name":"Sundre i hundre"}]},{"@type":"WebSite","@id":"https:\/\/www.visital.no\/#website","url":"https:\/\/www.visital.no\/","name":"Besuchen Sie \u00c5l","description":"","publisher":{"@id":"https:\/\/www.visital.no\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visital.no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.visital.no\/#organization","name":"Besuchen Sie \u00c5l","url":"https:\/\/www.visital.no\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.visital.no\/#\/schema\/logo\/image\/","url":"https:\/\/www.visital.no\/wp-content\/uploads\/2024\/11\/al-i-hallingdal-logo.svg","contentUrl":"https:\/\/www.visital.no\/wp-content\/uploads\/2024\/11\/al-i-hallingdal-logo.svg","width":258,"height":100,"caption":"Visit \u00c5l"},"image":{"@id":"https:\/\/www.visital.no\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/visitalihallingdal\/","https:\/\/instagram.com\/visitalihallingdal\/","https:\/\/youtube.com\/user\/alutvikling"]}]}},"_links":{"self":[{"href":"https:\/\/www.visital.no\/de\/wp-json\/wp\/v2\/tribe_events\/3905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.visital.no\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.visital.no\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.visital.no\/de\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":2,"href":"https:\/\/www.visital.no\/de\/wp-json\/wp\/v2\/tribe_events\/3905\/revisions"}],"predecessor-version":[{"id":3989,"href":"https:\/\/www.visital.no\/de\/wp-json\/wp\/v2\/tribe_events\/3905\/revisions\/3989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visital.no\/de\/wp-json\/wp\/v2\/media\/3902"}],"wp:attachment":[{"href":"https:\/\/www.visital.no\/de\/wp-json\/wp\/v2\/media?parent=3905"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.visital.no\/de\/wp-json\/wp\/v2\/tags?post=3905"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.visital.no\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=3905"}],"curies":[{"name":"WordPress","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}